{"id":823,"date":"2026-02-27T20:31:03","date_gmt":"2026-02-27T19:31:03","guid":{"rendered":"https:\/\/www.lequeerlieu.fr\/?page_id=823"},"modified":"2026-05-19T10:39:16","modified_gmt":"2026-05-19T08:39:16","slug":"le-cafe","status":"publish","type":"page","link":"https:\/\/www.lequeerlieu.fr\/index.php\/le-cafe\/","title":{"rendered":"Le caf\u00e9 partag\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Queer Lieu a pris ses quartiers \u00e0 la Bourse du travail de Saint-Denis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venez boire un caf\u00e9, lire, travailler, rencontrer de nouvelles personnes ou retrouver vos ami\u00b7es !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2139\ufe0f Nous sommes encore dans une phase d&rsquo;exp\u00e9rimentation. On prend nos marques ! L&rsquo;espace et le fonctionnement peuvent donc \u00e9voluer petit \u00e0 petit.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a57de94bd637&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57de94bf4bc&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57de94bf4bc\" class=\"wp-block-image size-large is-style-default wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1130\" src=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/cafe-1024x768.jpg\" alt=\"Le caf\u00e9 partag\u00e9\" class=\"wp-image-1130\" srcset=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/cafe-1024x768.jpg 1024w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/cafe-300x225.jpg 300w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/cafe-768x576.jpg 768w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/cafe.jpg 1371w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Le caf\u00e9 partag\u00e9<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57de94bf9cc&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57de94bf9cc\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"936\" height=\"722\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1131\" src=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/espace_jeux.jpg\" alt=\"L'espace jeux\" class=\"wp-image-1131\" srcset=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/espace_jeux.jpg 936w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/espace_jeux-300x231.jpg 300w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/espace_jeux-768x592.jpg 768w\" sizes=\"auto, (max-width: 936px) 100vw, 936px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">L&rsquo;espace enfants<\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57de94bfe68&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57de94bfe68\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"917\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1132\" src=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/jardin-917x1024.jpg\" alt=\"Le jardin de la bourse\" class=\"wp-image-1132\" srcset=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/jardin-917x1024.jpg 917w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/jardin-269x300.jpg 269w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/jardin-768x858.jpg 768w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2026\/03\/jardin.jpg 1058w\" sizes=\"auto, (max-width: 917px) 100vw, 917px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Le jardin de la Bourse du Travail<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">C&rsquo;est quand ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; <strong>Le jeudi soir de 18h \u00e0 21h<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; <strong>Le samedi de 14h \u00e0 20h<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; <strong>Le dimanche de 14h \u00e0 18h<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">C&rsquo;est o\u00f9 ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83e\udded 9-11 Rue G\u00e9nin 93200 Saint-Denis <br>Prenez l&rsquo;entr\u00e9e principale de bourse du travail et suivez l&rsquo;affichage&#8230; on est pas loin !<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"425\" height=\"350\" src=\"https:\/\/www.openstreetmap.org\/export\/embed.html?bbox=2.352683544158936%2C48.92889116642128%2C2.355676889419556%2C48.929951998586965&amp;layer=mapnik&amp;marker=48.92942158532146%2C2.3541802167892456\" style=\"border: 1px solid black\"><\/iframe><br\/><small><a href=\"https:\/\/www.openstreetmap.org\/?mlat=48.929422&amp;mlon=2.354180#map=19\/48.929422\/2.354180\">Afficher une carte plus grande<\/a><\/small>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Qu&rsquo;est-ce que l&rsquo;on peut boire \/ manger ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Voici la carte du moment, elle peut varier en fonction des approvisionnements et des envies !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83e\ude99 Les prix sont donn\u00e9s \u00e0 titre indicatif, c&rsquo;est-\u00e0-dire que vous pouvez donner plus ou moins en fonction de vos moyens. C&rsquo;est le principe du <a href=\"https:\/\/www.lequeerlieu.fr\/index.php\/2026\/04\/22\/avec-le-prix-libre-largent-gagne-en-sens\/\" data-type=\"post\" data-id=\"1264\">prix libre et conscient<\/a> !<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Caf\u00e9 \/ Th\u00e9 \/ Infusion : 1 \u20ac<\/li>\n\n\n\n<li>Sirop \u00e0 l&rsquo;eau : 1 \u20ac<\/li>\n\n\n\n<li>Diabolo : 2 \u20ac<\/li>\n\n\n\n<li>Limonade : 2 \u20ac<\/li>\n\n\n\n<li>Bubule le K\u00e9fir : 2 \u20ac<\/li>\n\n\n\n<li>Bi\u00e8re sans alcool : 3 \u20ac<\/li>\n\n\n\n<li>Grignottes du moment (chips, cacahu\u00e8tes, etc.) : 1\u20ac&nbsp;la portion<\/li>\n\n\n\n<li>Go\u00fbter sucr\u00e9 : voir l&rsquo;ardoise du moment<br><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf31 Notre carte est sans alcool et les produits propos\u00e9s sont le plus possible locaux et \/ ou bio<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Quel est le fonctionnement du caf\u00e9 partag\u00e9 ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Des b\u00e9n\u00e9voles de l&rsquo;association sont l\u00e0 pour vous accueillir, vous pr\u00e9senter le caf\u00e9 et nos actions. En dehors de certains \u00e9v\u00e8nements, le caf\u00e9 fonctionne en auto-gestion : chacun\u00b7e est invit\u00e9 \u00e0 se servir librement, faire sa vaisselle, etc. Il est possible de payer en esp\u00e8ces ou par carte bancaire. L\u00e0 aussi, c&rsquo;est la confiance et l&rsquo;autonomie qui guident la vie du lieu mais vous trouverez toujours quelqu&rsquo;un\u00b7e pour vous expliquer et vous accompagner si besoin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u265f\ufe0f Au Queer Lieu, vous trouverez \u00e9galement une biblioth\u00e8que partag\u00e9e, des jeux de soci\u00e9t\u00e9, une boite \u00e0 don, une grainoth\u00e8que, une machine \u00e0 coudre et du mat\u00e9riel cr\u00e9atifs&#8230; un espace est aussi accessible pour les enfants avec des jeux et des livres car il nous tient \u00e0 c\u0153ur de construire un espace inclusif -aussi- pour les plus jeunes ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83e\udef6\ufe0f Tous ces \u00e9l\u00e9ments ont pu \u00eatre mis en place gr\u00e2ce aux dons et \u00e0 la g\u00e9n\u00e9rosit\u00e9 de nombreux\u00b7ses visiteur\u00b7ices ! <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Qui peut venir au Queer Lieu ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La porte est ouverte \u00e0 toutes et \u00e0 tous, bienvenue !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc49 Une seule condition : s&rsquo;engager \u00e0 respecter la charte de vie du lieu, les valeurs de l&rsquo;association et toute personne qui fr\u00e9quente le caf\u00e9, quelqu&rsquo;iel soit et quelques soit son parcours.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Queer Lieu est port\u00e9 par \/ pour les personnes LGBTQIA+ et souhaite proposer un espace safe et convivial pour la communaut\u00e9. Nos alli\u00e9\u00b7es sont \u00e9videmment les bienvenu\u00b7es de m\u00eame que <a href=\"https:\/\/www.lequeerlieu.fr\/index.php\/enjeux-lgbtqia\/\" data-type=\"page\" data-id=\"539\">celles et ceux qui veulent le devenir<\/a> !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Queer Lieu a pris ses quartiers \u00e0 la Bourse du travail de Saint-Denis. Venez boire un caf\u00e9, lire, travailler, rencontrer de nouvelles personnes ou retrouver vos ami\u00b7es ! \u2139\ufe0f &#8230; <a title=\"Le caf\u00e9 partag\u00e9\" class=\"read-more\" href=\"https:\/\/www.lequeerlieu.fr\/index.php\/le-cafe\/\" aria-label=\"En savoir plus sur Le caf\u00e9 partag\u00e9\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-823","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/pages\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=823"}],"version-history":[{"count":68,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/pages\/823\/revisions"}],"predecessor-version":[{"id":1413,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/pages\/823\/revisions\/1413"}],"wp:attachment":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}