{"id":479,"date":"2025-12-02T14:49:17","date_gmt":"2025-12-02T13:49:17","guid":{"rendered":"https:\/\/www.lequeerlieu.fr\/?p=479"},"modified":"2025-12-02T14:50:15","modified_gmt":"2025-12-02T13:50:15","slug":"construisons-le-projet-ensemble","status":"publish","type":"post","link":"https:\/\/www.lequeerlieu.fr\/index.php\/2025\/12\/02\/construisons-le-projet-ensemble\/","title":{"rendered":"Construisons le projet ensemble !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fonctionnement, gouvernance, \u00e9v\u00e8nements, accessibilit\u00e9, locaux et am\u00e9nagement&#8230; inventons ensemble Le Queer Lieu ! \u00c0 partir de janvier 2026, des r\u00e9unions r\u00e9guli\u00e8res permettront de construire tous les aspects du projet de mani\u00e8re collective. Les compte-rendus de ces travaux seront disponibles sur le site internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces moments sont ouverts \u00e0 toutes et \u00e0 tous. Dans la mesure du possible, nous vous remercions cependant de vous inscrire pour faciliter l&rsquo;organisation de la soir\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Premi\u00e8re r\u00e9union :<\/strong> <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-482\" style=\"width: 20px;\" src=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/calendar_small.png\" alt=\"\" srcset=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/calendar_small.png 300w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/calendar_small-150x150.png 150w\" sizes=\"auto, (max-width: 20px) 100vw, 20px\" \/> Jeudi 8 janvier de 19h \u00e0 21h<br><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-484\" style=\"width: 20px;\" src=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/loc_small.png\" alt=\"\" srcset=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/loc_small.png 300w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/loc_small-150x150.png 150w\" sizes=\"auto, (max-width: 20px) 100vw, 20px\" \/> Lieu pr\u00e9cis\u00e9 prochainement<br><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"wp-image-483\" style=\"width: 20px;\" src=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/infos_small.png\" alt=\"\" srcset=\"https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/infos_small.png 300w, https:\/\/www.lequeerlieu.fr\/wp-content\/uploads\/2025\/11\/infos_small-150x150.png 150w\" sizes=\"auto, (max-width: 20px) 100vw, 20px\" \/> Ouvert \u00e0 toutes et \u00e0 tous, inscription recommand\u00e9e pour faciliter l&rsquo;organisation<\/p>\n<\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Je m&rsquo;inscris !<\/h4>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f497-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"497\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/posts\/479#wpcf7-f497-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"497\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f497-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Votre pr\u00e9nom<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"prenom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"prenom\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre nom<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nom\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre e-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre num\u00e9ro de t\u00e9l\u00e9phone (facultatif)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telephone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telephone\" \/><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fonctionnement, gouvernance, \u00e9v\u00e8nements, accessibilit\u00e9, locaux et am\u00e9nagement&#8230; inventons ensemble Le Queer Lieu ! \u00c0 partir de janvier 2026, des r\u00e9unions r\u00e9guli\u00e8res permettront de construire tous les aspects du projet de &#8230; <a title=\"Construisons le projet ensemble !\" class=\"read-more\" href=\"https:\/\/www.lequeerlieu.fr\/index.php\/2025\/12\/02\/construisons-le-projet-ensemble\/\" aria-label=\"En savoir plus sur Construisons le projet ensemble !\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":505,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus"],"_links":{"self":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":19,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"predecessor-version":[{"id":658,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/posts\/479\/revisions\/658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/media\/505"}],"wp:attachment":[{"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lequeerlieu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}